{"id":1,"date":"2025-12-24T12:30:25","date_gmt":"2025-12-24T12:30:25","guid":{"rendered":"http:\/\/test26.jssupportticket.com\/?p=1"},"modified":"2025-12-24T12:30:25","modified_gmt":"2025-12-24T12:30:25","slug":"hello-world","status":"publish","type":"post","link":"https:\/\/test26.jssupportticket.com\/index.php\/2025\/12\/24\/hello-world\/","title":{"rendered":"Hello world!"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Welcome to WordPress. This is your first post. Edit or delete it, then start writing!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Welcome to WordPress. This is your first post. Edit or delete it, then start writing!<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/test26.jssupportticket.com\/index.php\/wp-json\/wp\/v2\/posts\/1","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/test26.jssupportticket.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/test26.jssupportticket.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/test26.jssupportticket.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/test26.jssupportticket.com\/index.php\/wp-json\/wp\/v2\/comments?post=1"}],"version-history":[{"count":0,"href":"https:\/\/test26.jssupportticket.com\/index.php\/wp-json\/wp\/v2\/posts\/1\/revisions"}],"wp:attachment":[{"href":"https:\/\/test26.jssupportticket.com\/index.php\/wp-json\/wp\/v2\/media?parent=1"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/test26.jssupportticket.com\/index.php\/wp-json\/wp\/v2\/categories?post=1"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/test26.jssupportticket.com\/index.php\/wp-json\/wp\/v2\/tags?post=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}